{"id":8238,"date":"2026-05-09T15:45:56","date_gmt":"2026-05-09T15:45:56","guid":{"rendered":"https:\/\/modelbrazil.com.br\/?p=8238"},"modified":"2026-05-09T15:45:56","modified_gmt":"2026-05-09T15:45:56","slug":"erika-januza-ganha-homenagem-romantica-de-arlindinho-ao-celebrar-41-anos","status":"publish","type":"post","link":"https:\/\/modelbrazil.com.br\/index.php\/2026\/05\/09\/erika-januza-ganha-homenagem-romantica-de-arlindinho-ao-celebrar-41-anos\/","title":{"rendered":"Erika Januza ganha homenagem rom\u00e2ntica de Arlindinho ao celebrar 41 anos"},"content":{"rendered":"\n<p>A atriz Erika Januza comemorou a chegada dos 41 anos em clima de amor, f\u00e9 e celebra\u00e7\u00e3o ao lado de pessoas pr\u00f3ximas e do namorado, Arlindinho.<\/p>\n\n\n\n<p>Nas redes sociais, Erika mostrou alguns momentos especiais do anivers\u00e1rio, que come\u00e7ou com uma missa celebrada por Padre Marcelo Rossi, em S\u00e3o Paulo. A atriz compartilhou uma foto ao lado do sacerdote e agradeceu pelo novo ciclo.<\/p>\n\n\n\n<p>Mais tarde, ela acompanhou Arlindinho durante um show e celebrou a nova fase cercada de amigos, m\u00fasica e mensagens de carinho.<\/p>\n\n\n\n<p>O casal tamb\u00e9m viveu um momento rom\u00e2ntico durante um jantar especial. Entre os detalhes compartilhados pela atriz estavam ta\u00e7as de espumante e um presente de luxo recebido da Gucci.<\/p>\n\n\n\n<p>Nas redes, Arlindinho fez quest\u00e3o de homenagear a namorada com uma declara\u00e7\u00e3o apaixonada, emocionando os seguidores do casal.<\/p>\n\n\n\n<p>A comemora\u00e7\u00e3o acontece poucas semanas ap\u00f3s Erika Januza enfrentar um problema de sa\u00fade. Recentemente, a atriz precisou ser internada ap\u00f3s ser diagnosticada com pielonefrite, uma infec\u00e7\u00e3o nos rins.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A atriz Erika Januza comemorou a chegada dos 41 anos em clima de amor, f\u00e9 e celebra\u00e7\u00e3o ao lado de pessoas pr\u00f3ximas e do namorado, Arlindinho. Nas redes sociais, Erika mostrou alguns momentos especiais do anivers\u00e1rio, que come\u00e7ou com uma missa celebrada por Padre Marcelo Rossi, em S\u00e3o Paulo. A atriz compartilhou uma foto ao \u2026<\/p>\n","protected":false},"author":2,"featured_media":8237,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[],"class_list":["post-8238","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-famosos"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.3.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Erika Januza ganha homenagem rom\u00e2ntica de Arlindinho ao celebrar 41 anos - Model Brazil<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/modelbrazil.com.br\/index.php\/2026\/05\/09\/erika-januza-ganha-homenagem-romantica-de-arlindinho-ao-celebrar-41-anos\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Erika Januza ganha homenagem rom\u00e2ntica de Arlindinho ao celebrar 41 anos - Model Brazil\" \/>\n<meta property=\"og:description\" content=\"A atriz Erika Januza comemorou a chegada dos 41 anos em clima de amor, f\u00e9 e celebra\u00e7\u00e3o ao lado de pessoas pr\u00f3ximas e do namorado, Arlindinho. Nas redes sociais, Erika mostrou alguns momentos especiais do anivers\u00e1rio, que come\u00e7ou com uma missa celebrada por Padre Marcelo Rossi, em S\u00e3o Paulo. A atriz compartilhou uma foto ao \u2026\" \/>\n<meta property=\"og:url\" content=\"https:\/\/modelbrazil.com.br\/index.php\/2026\/05\/09\/erika-januza-ganha-homenagem-romantica-de-arlindinho-ao-celebrar-41-anos\/\" \/>\n<meta property=\"og:site_name\" content=\"Model Brazil\" \/>\n<meta property=\"article:published_time\" content=\"2026-05-09T15:45:56+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/modelbrazil.com.br\/wp-content\/uploads\/2026\/05\/erika-januza-comemorou-aniversario-com-missa-e-ganhou-carinho-do-namorado-arlindinho-1778279956819_v2_900x506.jpg.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"900\" \/>\n\t<meta property=\"og:image:height\" content=\"506\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"author\" content=\"assessoriadefamosos\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"assessoriadefamosos\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/modelbrazil.com.br\/index.php\/2026\/05\/09\/erika-januza-ganha-homenagem-romantica-de-arlindinho-ao-celebrar-41-anos\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/modelbrazil.com.br\/index.php\/2026\/05\/09\/erika-januza-ganha-homenagem-romantica-de-arlindinho-ao-celebrar-41-anos\/\"},\"author\":{\"name\":\"assessoriadefamosos\",\"@id\":\"https:\/\/modelbrazil.com.br\/#\/schema\/person\/871fd7d9e18a3653430103bf4378d5f6\"},\"headline\":\"Erika Januza ganha homenagem rom\u00e2ntica de Arlindinho ao celebrar 41 anos\",\"datePublished\":\"2026-05-09T15:45:56+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/modelbrazil.com.br\/index.php\/2026\/05\/09\/erika-januza-ganha-homenagem-romantica-de-arlindinho-ao-celebrar-41-anos\/\"},\"wordCount\":185,\"publisher\":{\"@id\":\"https:\/\/modelbrazil.com.br\/#organization\"},\"image\":{\"@id\":\"https:\/\/modelbrazil.com.br\/index.php\/2026\/05\/09\/erika-januza-ganha-homenagem-romantica-de-arlindinho-ao-celebrar-41-anos\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/modelbrazil.com.br\/wp-content\/uploads\/2026\/05\/erika-januza-comemorou-aniversario-com-missa-e-ganhou-carinho-do-namorado-arlindinho-1778279956819_v2_900x506.jpg.webp\",\"articleSection\":[\"Famosos\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/modelbrazil.com.br\/index.php\/2026\/05\/09\/erika-januza-ganha-homenagem-romantica-de-arlindinho-ao-celebrar-41-anos\/\",\"url\":\"https:\/\/modelbrazil.com.br\/index.php\/2026\/05\/09\/erika-januza-ganha-homenagem-romantica-de-arlindinho-ao-celebrar-41-anos\/\",\"name\":\"Erika Januza ganha homenagem rom\u00e2ntica de Arlindinho ao celebrar 41 anos - Model Brazil\",\"isPartOf\":{\"@id\":\"https:\/\/modelbrazil.com.br\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/modelbrazil.com.br\/index.php\/2026\/05\/09\/erika-januza-ganha-homenagem-romantica-de-arlindinho-ao-celebrar-41-anos\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/modelbrazil.com.br\/index.php\/2026\/05\/09\/erika-januza-ganha-homenagem-romantica-de-arlindinho-ao-celebrar-41-anos\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/modelbrazil.com.br\/wp-content\/uploads\/2026\/05\/erika-januza-comemorou-aniversario-com-missa-e-ganhou-carinho-do-namorado-arlindinho-1778279956819_v2_900x506.jpg.webp\",\"datePublished\":\"2026-05-09T15:45:56+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/modelbrazil.com.br\/index.php\/2026\/05\/09\/erika-januza-ganha-homenagem-romantica-de-arlindinho-ao-celebrar-41-anos\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/modelbrazil.com.br\/index.php\/2026\/05\/09\/erika-januza-ganha-homenagem-romantica-de-arlindinho-ao-celebrar-41-anos\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/modelbrazil.com.br\/index.php\/2026\/05\/09\/erika-januza-ganha-homenagem-romantica-de-arlindinho-ao-celebrar-41-anos\/#primaryimage\",\"url\":\"https:\/\/modelbrazil.com.br\/wp-content\/uploads\/2026\/05\/erika-januza-comemorou-aniversario-com-missa-e-ganhou-carinho-do-namorado-arlindinho-1778279956819_v2_900x506.jpg.webp\",\"contentUrl\":\"https:\/\/modelbrazil.com.br\/wp-content\/uploads\/2026\/05\/erika-januza-comemorou-aniversario-com-missa-e-ganhou-carinho-do-namorado-arlindinho-1778279956819_v2_900x506.jpg.webp\",\"width\":900,\"height\":506},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/modelbrazil.com.br\/index.php\/2026\/05\/09\/erika-januza-ganha-homenagem-romantica-de-arlindinho-ao-celebrar-41-anos\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/modelbrazil.com.br\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Erika Januza ganha homenagem rom\u00e2ntica de Arlindinho ao celebrar 41 anos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/modelbrazil.com.br\/#website\",\"url\":\"https:\/\/modelbrazil.com.br\/\",\"name\":\"Model Brazil\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/modelbrazil.com.br\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/modelbrazil.com.br\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/modelbrazil.com.br\/#organization\",\"name\":\"Model Brazil\",\"url\":\"https:\/\/modelbrazil.com.br\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/modelbrazil.com.br\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/modelbrazil.com.br\/wp-content\/uploads\/2025\/06\/cropped-aae972fb-e005-4003-b039-2676e1ba2afc.jpg\",\"contentUrl\":\"https:\/\/modelbrazil.com.br\/wp-content\/uploads\/2025\/06\/cropped-aae972fb-e005-4003-b039-2676e1ba2afc.jpg\",\"width\":1024,\"height\":655,\"caption\":\"Model Brazil\"},\"image\":{\"@id\":\"https:\/\/modelbrazil.com.br\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/modelbrazil.com.br\/#\/schema\/person\/871fd7d9e18a3653430103bf4378d5f6\",\"name\":\"assessoriadefamosos\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/modelbrazil.com.br\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/a7acbdffcfbbae7240e59f47fe511ec5f5d8c252c779f0b8d9ab02a9e1d8c5ed?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/a7acbdffcfbbae7240e59f47fe511ec5f5d8c252c779f0b8d9ab02a9e1d8c5ed?s=96&d=mm&r=g\",\"caption\":\"assessoriadefamosos\"},\"url\":\"https:\/\/modelbrazil.com.br\/index.php\/author\/assessoriadefamosos\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Erika Januza ganha homenagem rom\u00e2ntica de Arlindinho ao celebrar 41 anos - Model Brazil","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/modelbrazil.com.br\/index.php\/2026\/05\/09\/erika-januza-ganha-homenagem-romantica-de-arlindinho-ao-celebrar-41-anos\/","og_locale":"pt_BR","og_type":"article","og_title":"Erika Januza ganha homenagem rom\u00e2ntica de Arlindinho ao celebrar 41 anos - Model Brazil","og_description":"A atriz Erika Januza comemorou a chegada dos 41 anos em clima de amor, f\u00e9 e celebra\u00e7\u00e3o ao lado de pessoas pr\u00f3ximas e do namorado, Arlindinho. Nas redes sociais, Erika mostrou alguns momentos especiais do anivers\u00e1rio, que come\u00e7ou com uma missa celebrada por Padre Marcelo Rossi, em S\u00e3o Paulo. A atriz compartilhou uma foto ao \u2026","og_url":"https:\/\/modelbrazil.com.br\/index.php\/2026\/05\/09\/erika-januza-ganha-homenagem-romantica-de-arlindinho-ao-celebrar-41-anos\/","og_site_name":"Model Brazil","article_published_time":"2026-05-09T15:45:56+00:00","og_image":[{"width":900,"height":506,"url":"https:\/\/modelbrazil.com.br\/wp-content\/uploads\/2026\/05\/erika-januza-comemorou-aniversario-com-missa-e-ganhou-carinho-do-namorado-arlindinho-1778279956819_v2_900x506.jpg.webp","type":"image\/webp"}],"author":"assessoriadefamosos","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"assessoriadefamosos","Est. tempo de leitura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/modelbrazil.com.br\/index.php\/2026\/05\/09\/erika-januza-ganha-homenagem-romantica-de-arlindinho-ao-celebrar-41-anos\/#article","isPartOf":{"@id":"https:\/\/modelbrazil.com.br\/index.php\/2026\/05\/09\/erika-januza-ganha-homenagem-romantica-de-arlindinho-ao-celebrar-41-anos\/"},"author":{"name":"assessoriadefamosos","@id":"https:\/\/modelbrazil.com.br\/#\/schema\/person\/871fd7d9e18a3653430103bf4378d5f6"},"headline":"Erika Januza ganha homenagem rom\u00e2ntica de Arlindinho ao celebrar 41 anos","datePublished":"2026-05-09T15:45:56+00:00","mainEntityOfPage":{"@id":"https:\/\/modelbrazil.com.br\/index.php\/2026\/05\/09\/erika-januza-ganha-homenagem-romantica-de-arlindinho-ao-celebrar-41-anos\/"},"wordCount":185,"publisher":{"@id":"https:\/\/modelbrazil.com.br\/#organization"},"image":{"@id":"https:\/\/modelbrazil.com.br\/index.php\/2026\/05\/09\/erika-januza-ganha-homenagem-romantica-de-arlindinho-ao-celebrar-41-anos\/#primaryimage"},"thumbnailUrl":"https:\/\/modelbrazil.com.br\/wp-content\/uploads\/2026\/05\/erika-januza-comemorou-aniversario-com-missa-e-ganhou-carinho-do-namorado-arlindinho-1778279956819_v2_900x506.jpg.webp","articleSection":["Famosos"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/modelbrazil.com.br\/index.php\/2026\/05\/09\/erika-januza-ganha-homenagem-romantica-de-arlindinho-ao-celebrar-41-anos\/","url":"https:\/\/modelbrazil.com.br\/index.php\/2026\/05\/09\/erika-januza-ganha-homenagem-romantica-de-arlindinho-ao-celebrar-41-anos\/","name":"Erika Januza ganha homenagem rom\u00e2ntica de Arlindinho ao celebrar 41 anos - Model Brazil","isPartOf":{"@id":"https:\/\/modelbrazil.com.br\/#website"},"primaryImageOfPage":{"@id":"https:\/\/modelbrazil.com.br\/index.php\/2026\/05\/09\/erika-januza-ganha-homenagem-romantica-de-arlindinho-ao-celebrar-41-anos\/#primaryimage"},"image":{"@id":"https:\/\/modelbrazil.com.br\/index.php\/2026\/05\/09\/erika-januza-ganha-homenagem-romantica-de-arlindinho-ao-celebrar-41-anos\/#primaryimage"},"thumbnailUrl":"https:\/\/modelbrazil.com.br\/wp-content\/uploads\/2026\/05\/erika-januza-comemorou-aniversario-com-missa-e-ganhou-carinho-do-namorado-arlindinho-1778279956819_v2_900x506.jpg.webp","datePublished":"2026-05-09T15:45:56+00:00","breadcrumb":{"@id":"https:\/\/modelbrazil.com.br\/index.php\/2026\/05\/09\/erika-januza-ganha-homenagem-romantica-de-arlindinho-ao-celebrar-41-anos\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/modelbrazil.com.br\/index.php\/2026\/05\/09\/erika-januza-ganha-homenagem-romantica-de-arlindinho-ao-celebrar-41-anos\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/modelbrazil.com.br\/index.php\/2026\/05\/09\/erika-januza-ganha-homenagem-romantica-de-arlindinho-ao-celebrar-41-anos\/#primaryimage","url":"https:\/\/modelbrazil.com.br\/wp-content\/uploads\/2026\/05\/erika-januza-comemorou-aniversario-com-missa-e-ganhou-carinho-do-namorado-arlindinho-1778279956819_v2_900x506.jpg.webp","contentUrl":"https:\/\/modelbrazil.com.br\/wp-content\/uploads\/2026\/05\/erika-januza-comemorou-aniversario-com-missa-e-ganhou-carinho-do-namorado-arlindinho-1778279956819_v2_900x506.jpg.webp","width":900,"height":506},{"@type":"BreadcrumbList","@id":"https:\/\/modelbrazil.com.br\/index.php\/2026\/05\/09\/erika-januza-ganha-homenagem-romantica-de-arlindinho-ao-celebrar-41-anos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/modelbrazil.com.br\/"},{"@type":"ListItem","position":2,"name":"Erika Januza ganha homenagem rom\u00e2ntica de Arlindinho ao celebrar 41 anos"}]},{"@type":"WebSite","@id":"https:\/\/modelbrazil.com.br\/#website","url":"https:\/\/modelbrazil.com.br\/","name":"Model Brazil","description":"","publisher":{"@id":"https:\/\/modelbrazil.com.br\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/modelbrazil.com.br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/modelbrazil.com.br\/#organization","name":"Model Brazil","url":"https:\/\/modelbrazil.com.br\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/modelbrazil.com.br\/#\/schema\/logo\/image\/","url":"https:\/\/modelbrazil.com.br\/wp-content\/uploads\/2025\/06\/cropped-aae972fb-e005-4003-b039-2676e1ba2afc.jpg","contentUrl":"https:\/\/modelbrazil.com.br\/wp-content\/uploads\/2025\/06\/cropped-aae972fb-e005-4003-b039-2676e1ba2afc.jpg","width":1024,"height":655,"caption":"Model Brazil"},"image":{"@id":"https:\/\/modelbrazil.com.br\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/modelbrazil.com.br\/#\/schema\/person\/871fd7d9e18a3653430103bf4378d5f6","name":"assessoriadefamosos","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/modelbrazil.com.br\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/a7acbdffcfbbae7240e59f47fe511ec5f5d8c252c779f0b8d9ab02a9e1d8c5ed?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a7acbdffcfbbae7240e59f47fe511ec5f5d8c252c779f0b8d9ab02a9e1d8c5ed?s=96&d=mm&r=g","caption":"assessoriadefamosos"},"url":"https:\/\/modelbrazil.com.br\/index.php\/author\/assessoriadefamosos\/"}]}},"_links":{"self":[{"href":"https:\/\/modelbrazil.com.br\/index.php\/wp-json\/wp\/v2\/posts\/8238","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/modelbrazil.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/modelbrazil.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/modelbrazil.com.br\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/modelbrazil.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=8238"}],"version-history":[{"count":1,"href":"https:\/\/modelbrazil.com.br\/index.php\/wp-json\/wp\/v2\/posts\/8238\/revisions"}],"predecessor-version":[{"id":8239,"href":"https:\/\/modelbrazil.com.br\/index.php\/wp-json\/wp\/v2\/posts\/8238\/revisions\/8239"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/modelbrazil.com.br\/index.php\/wp-json\/wp\/v2\/media\/8237"}],"wp:attachment":[{"href":"https:\/\/modelbrazil.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=8238"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/modelbrazil.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=8238"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/modelbrazil.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=8238"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}